{"id":3577,"date":"2019-12-12T13:17:33","date_gmt":"2019-12-12T13:17:33","guid":{"rendered":"https:\/\/server-sanco.it\/?post_type=product&#038;p=3577"},"modified":"2024-06-28T12:18:31","modified_gmt":"2024-06-28T10:18:31","slug":"multifunction-analogic-timer","status":"publish","type":"product","link":"https:\/\/exom-electric.it\/en\/prodotto\/temporizzatori-analogico-multifunzione\/","title":{"rendered":"Analogic timer H3CR, ANLY"},"content":{"rendered":"<ul>\n<li>\u00a08 output selectable modes<\/li>\n<li>Selectable time range from 1 second to 300 hours<\/li>\n<li>Operating voltage: 24\/240 AC\/DC<\/li>\n<li>Contact rating: 5A  250VAC<\/li>\n<li>Reset time: max 0,1 sec<\/li>\n<li>Adapter: Y50<\/li>\n<li>8 pins octal\/11 pins undecal<\/li>\n<li>Approvals: UL, CE<\/li>\n<li>Manufacturing: ANLY<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p class=\"translation-block\">Multifunction analogic timer.<\/p>","protected":false},"featured_media":5362,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[327],"product_tag":[1321,1323,1325,1317,1319,1315],"class_list":{"0":"post-3577","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-temporizzatori-elettronici","7":"product_tag-analogic-timer","8":"product_tag-controllo-industriale","9":"product_tag-industrial-control","10":"product_tag-temporizzatore","11":"product_tag-temporizzatore-analogico","12":"product_tag-timer","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temporizzatore analogico Multifunzione H3CR - EXO.M<\/title>\n<meta name=\"description\" content=\"Temporizzatore analogico Multifunzione, 8 uscite selezionabili per varie applicazioni, multiscala selezionabile da 1s a 300, spinatura octal\/undecal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exom-electric.it\/en\/product\/multifunction-analogic-timer\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temporizzatore analogico Multifunzione H3CR - EXO.M\" \/>\n<meta property=\"og:description\" content=\"Temporizzatore analogico Multifunzione, 8 uscite selezionabili per varie applicazioni, multiscala selezionabile da 1s a 300, spinatura octal\/undecal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exom-electric.it\/en\/product\/multifunction-analogic-timer\/\" \/>\n<meta property=\"og:site_name\" content=\"EXOM ELECTRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exom.electric\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-28T10:18:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exom-electric.it\/wp-content\/uploads\/2019\/12\/H3CR-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/\",\"name\":\"Temporizzatore analogico Multifunzione H3CR - EXO.M\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/H3CR-1.png\",\"datePublished\":\"2019-12-12T13:17:33+00:00\",\"dateModified\":\"2024-06-28T10:18:31+00:00\",\"description\":\"Temporizzatore analogico Multifunzione, 8 uscite selezionabili per varie applicazioni, multiscala selezionabile da 1s a 300, spinatura octal\\\/undecal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/H3CR-1.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/H3CR-1.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/temporizzatori-analogico-multifunzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/catalogo-exom\\\/catalogo-prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Temporizzatore analogico H3CR, ANLY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"name\":\"EXOM ELECTRIC\",\"description\":\"Automation components - Industrial cable processing\",\"publisher\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exom-electric.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\",\"name\":\"Exo.m Electric\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"width\":214,\"height\":100,\"caption\":\"Exo.m Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exom.electric\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H3CR multifunction analogic timer - EXO.M","description":"Multifunction analogic timer, 8 output selectable modes, selectable time range from 1 second to 300 hours, 8 pins octal\/11 pins undecal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exom-electric.it\/en\/product\/multifunction-analogic-timer\/","og_locale":"en_GB","og_type":"article","og_title":"Temporizzatore analogico Multifunzione H3CR - EXO.M","og_description":"Temporizzatore analogico Multifunzione, 8 uscite selezionabili per varie applicazioni, multiscala selezionabile da 1s a 300, spinatura octal\/undecal","og_url":"https:\/\/exom-electric.it\/en\/product\/multifunction-analogic-timer\/","og_site_name":"EXOM ELECTRIC","article_publisher":"https:\/\/www.facebook.com\/exom.electric\/","article_modified_time":"2024-06-28T10:18:31+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2019\/12\/H3CR-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/","url":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/","name":"H3CR multifunction analogic timer - EXO.M","isPartOf":{"@id":"https:\/\/exom-electric.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/#primaryimage"},"image":{"@id":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/#primaryimage"},"thumbnailUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2019\/12\/H3CR-1.png","datePublished":"2019-12-12T13:17:33+00:00","dateModified":"2024-06-28T10:18:31+00:00","description":"Multifunction analogic timer, 8 output selectable modes, selectable time range from 1 second to 300 hours, 8 pins octal\/11 pins undecal","breadcrumb":{"@id":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/#primaryimage","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2019\/12\/H3CR-1.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2019\/12\/H3CR-1.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/exom-electric.it\/prodotto\/temporizzatori-analogico-multifunzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exom-electric.it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/exom-electric.it\/catalogo-exom\/catalogo-prodotti\/"},{"@type":"ListItem","position":3,"name":"Temporizzatore analogico H3CR, ANLY"}]},{"@type":"WebSite","@id":"https:\/\/exom-electric.it\/#website","url":"https:\/\/exom-electric.it\/","name":"EXOM ELECTRIC","description":"Automation components - Industrial cable processing","publisher":{"@id":"https:\/\/exom-electric.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exom-electric.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/exom-electric.it\/#organization","name":"Exo.m Electric","url":"https:\/\/exom-electric.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","width":214,"height":100,"caption":"Exo.m Electric"},"image":{"@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exom.electric\/"]}]}},"_links":{"self":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product\/3577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/media\/5362"}],"wp:attachment":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_brand?post=3577"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat?post=3577"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_tag?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}