{"id":3812,"date":"2020-02-21T14:10:52","date_gmt":"2020-02-21T14:10:52","guid":{"rendered":"https:\/\/server-sanco.it\/?post_type=product&#038;p=3812"},"modified":"2026-02-03T16:07:51","modified_gmt":"2026-02-03T15:07:51","slug":"ac-axial-fan-fy15050-172x150x51-mm-flyfans","status":"publish","type":"product","link":"https:\/\/exom-electric.it\/en\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/","title":{"rendered":"AC tube axial fan FY15050, 172x150x51 mm, FLYFANS"},"content":{"rendered":"<ul>\n<li>AC tube axial fan FY15050, 172x150x51 mm<\/li>\n<li>Airflow: 187\/210 CFM  5,28\/5,93 m\u00b3\/min.<\/li>\n<li>Impedence protection<\/li>\n<li>Black diecast aluminium frame and glass fiber reinforced plastic blades UL94V0<\/li>\n<li>Protection degree: IP20<\/li>\n<li>Dielectric strength: 1500VAC<\/li>\n<li>Exclusive brand by EXOM<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Used in electromedical equipments, automotive, industrial applications, IT industry, digital equipments<\/p>","protected":false},"featured_media":10238,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1803],"product_tag":[1121,1045,1043,1041,1053,1125,1127,1123,1035],"class_list":{"0":"post-3812","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ventilatori-ac-2","7":"product_tag-ac-fan","8":"product_tag-assiale","9":"product_tag-axial","10":"product_tag-fan","11":"product_tag-industrial-fan","12":"product_tag-ventilatore-ac","13":"product_tag-ventilatore-assiale","14":"product_tag-ventilatore-industriale","15":"product_tag-ventola","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ventilatore assiale AC FY15050, 172x150x51mm, FlyFans<\/title>\n<meta name=\"description\" content=\"Ventilatore assiale FY15050, misure 172x150x51mm, flusso d&#039;aria 187\/210CFM\u00a0\u00a0 5,28\/5,9 m\u00b3\/min, marchio esclusivo Exom\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exom-electric.it\/en\/product\/ac-axial-fan-fy15050-172x150x51-mm-flyfans\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ventilatore assiale AC FY15050, 172x150x51mm, FlyFans\" \/>\n<meta property=\"og:description\" content=\"Ventilatore assiale FY15050, misure 172x150x51mm, flusso d&#039;aria 187\/210CFM\u00a0\u00a0 5,28\/5,9 m\u00b3\/min, marchio esclusivo Exom\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exom-electric.it\/en\/product\/ac-axial-fan-fy15050-172x150x51-mm-flyfans\/\" \/>\n<meta property=\"og:site_name\" content=\"EXOM ELECTRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exom.electric\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T15:07:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exom-electric.it\/wp-content\/uploads\/2023\/06\/7-FY15050.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/\",\"name\":\"Ventilatore assiale AC FY15050, 172x150x51mm, FlyFans\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/7-FY15050.png\",\"datePublished\":\"2020-02-21T14:10:52+00:00\",\"dateModified\":\"2026-02-03T15:07:51+00:00\",\"description\":\"Ventilatore assiale FY15050, misure 172x150x51mm, flusso d'aria 187\\\/210CFM\u00a0\u00a0 5,28\\\/5,9 m\u00b3\\\/min, marchio esclusivo Exom\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/7-FY15050.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/7-FY15050.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/ventola-fy15050-150x50-mm-flyfans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/catalogo-exom\\\/catalogo-prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ventilatore assiale AC FY15050, 172x150x51 mm, FLYFANS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"name\":\"EXOM ELECTRIC\",\"description\":\"Automation components - Industrial cable processing\",\"publisher\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exom-electric.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\",\"name\":\"Exo.m Electric\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"width\":214,\"height\":100,\"caption\":\"Exo.m Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exom.electric\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC tube axial fan FY15050, 172x150x51 mm, FLYFANS","description":"AC tube axial fan FY15050, size 172x150x51 mm, airflow 187\/210CFM\u00a0\u00a0 5,28\/5,9 m\u00b3\/min\u00a0, exclusive brand by EXOM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exom-electric.it\/en\/product\/ac-axial-fan-fy15050-172x150x51-mm-flyfans\/","og_locale":"en_GB","og_type":"article","og_title":"Ventilatore assiale AC FY15050, 172x150x51mm, FlyFans","og_description":"Ventilatore assiale FY15050, misure 172x150x51mm, flusso d'aria 187\/210CFM\u00a0\u00a0 5,28\/5,9 m\u00b3\/min, marchio esclusivo Exom","og_url":"https:\/\/exom-electric.it\/en\/product\/ac-axial-fan-fy15050-172x150x51-mm-flyfans\/","og_site_name":"EXOM ELECTRIC","article_publisher":"https:\/\/www.facebook.com\/exom.electric\/","article_modified_time":"2026-02-03T15:07:51+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2023\/06\/7-FY15050.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/","url":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/","name":"AC tube axial fan FY15050, 172x150x51 mm, FLYFANS","isPartOf":{"@id":"https:\/\/exom-electric.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/#primaryimage"},"image":{"@id":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/#primaryimage"},"thumbnailUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2023\/06\/7-FY15050.png","datePublished":"2020-02-21T14:10:52+00:00","dateModified":"2026-02-03T15:07:51+00:00","description":"AC tube axial fan FY15050, size 172x150x51 mm, airflow 187\/210CFM\u00a0\u00a0 5,28\/5,9 m\u00b3\/min\u00a0, exclusive brand by EXOM","breadcrumb":{"@id":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/#primaryimage","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2023\/06\/7-FY15050.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2023\/06\/7-FY15050.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/exom-electric.it\/prodotto\/ventola-fy15050-150x50-mm-flyfans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exom-electric.it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/exom-electric.it\/catalogo-exom\/catalogo-prodotti\/"},{"@type":"ListItem","position":3,"name":"Ventilatore assiale AC FY15050, 172x150x51 mm, FLYFANS"}]},{"@type":"WebSite","@id":"https:\/\/exom-electric.it\/#website","url":"https:\/\/exom-electric.it\/","name":"EXOM ELECTRIC","description":"Automation components - Industrial cable processing","publisher":{"@id":"https:\/\/exom-electric.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exom-electric.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/exom-electric.it\/#organization","name":"Exo.m Electric","url":"https:\/\/exom-electric.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","width":214,"height":100,"caption":"Exo.m Electric"},"image":{"@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exom.electric\/"]}]}},"_links":{"self":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product\/3812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/media\/10238"}],"wp:attachment":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/media?parent=3812"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_brand?post=3812"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat?post=3812"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_tag?post=3812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}