{"id":4083,"date":"2020-02-24T12:21:47","date_gmt":"2020-02-24T12:21:47","guid":{"rendered":"https:\/\/server-sanco.it\/?post_type=product&#038;p=4083"},"modified":"2026-03-03T14:03:52","modified_gmt":"2026-03-03T13:03:52","slug":"filters-for-fans","status":"publish","type":"product","link":"https:\/\/exom-electric.it\/en\/prodotto\/filtri-per-ventole\/","title":{"rendered":"Filtri per Ventilatori compatti serie XGNFF"},"content":{"rendered":"<ul>\n<li>Filtri per ventole serie XGNFF<\/li>\n<li>Dimensions: from 105x105 mm to 325x325 mm<\/li>\n<li>Material: PC\/ABS UL94-V0<\/li>\n<li>Self exthinguishing filter mat<\/li>\n<li>Protection degree: IP54 standard; option IP55<\/li>\n<li>Color ral 7035<\/li>\n<\/ul>\n<p>To assemble the drilling template, consult the technical data sheet.<\/p>","protected":false},"excerpt":{"rendered":"<p>Assembled on cooling units XVE series\nUsed as a filter protection for electric cabinets<\/p>","protected":false},"featured_media":13456,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[880],"product_tag":[380,1166,455,1178,1174,1172,1164,1162,1160,1176,1170,1168],"class_list":{"0":"post-4083","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessori-per-ventole","7":"product_tag-accessori","8":"product_tag-accessori-ventilazione","9":"product_tag-accessories","10":"product_tag-fan-accessories","11":"product_tag-fan-filter","12":"product_tag-filter","13":"product_tag-filtri","14":"product_tag-filtri-industriali","15":"product_tag-filtri-per-ventole","16":"product_tag-industrial-filter","17":"product_tag-portafiltro","18":"product_tag-ventilazione-industriale","20":"first","21":"instock","22":"taxable","23":"shipping-taxable","24":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filtri UL serie FF per ventilatori compatti, IP54 - EXOM<\/title>\n<meta name=\"description\" content=\"XGNFF, filtri di protezione completi per ventole, misure: da 105x105mm a 325x325mm, PC\/ABS UL94-V0, grado di protezione: IP54 standard, opzione IP55\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exom-electric.it\/en\/product\/filters-for-fans\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtri UL serie FF per ventilatori compatti, IP54 - EXOM\" \/>\n<meta property=\"og:description\" content=\"XGNFF, filtri di protezione completi per ventole, misure: da 105x105mm a 325x325mm, PC\/ABS UL94-V0, grado di protezione: IP54 standard, opzione IP55\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exom-electric.it\/en\/product\/filters-for-fans\/\" \/>\n<meta property=\"og:site_name\" content=\"EXOM ELECTRIC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exom.electric\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T13:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exom-electric.it\/wp-content\/uploads\/2020\/02\/XGNFF_gruppi_filtro_per-_ventilatori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/\",\"name\":\"Filtri UL serie FF per ventilatori compatti, IP54 - EXOM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/XGNFF_gruppi_filtro_per-_ventilatori.png\",\"datePublished\":\"2020-02-24T12:21:47+00:00\",\"dateModified\":\"2026-03-03T13:03:52+00:00\",\"description\":\"XGNFF, filtri di protezione completi per ventole, misure: da 105x105mm a 325x325mm, PC\\\/ABS UL94-V0, grado di protezione: IP54 standard, opzione IP55\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/XGNFF_gruppi_filtro_per-_ventilatori.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/XGNFF_gruppi_filtro_per-_ventilatori.png\",\"width\":300,\"height\":300,\"caption\":\"filtri e Gruppi filtro per quadri elettrici\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/prodotto\\\/filtri-per-ventole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/catalogo-exom\\\/catalogo-prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Filtri per Ventilatori compatti serie XGNFF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"name\":\"EXOM ELECTRIC\",\"description\":\"Automation components - Industrial cable processing\",\"publisher\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exom-electric.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\",\"name\":\"Exo.m Electric\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"width\":214,\"height\":100,\"caption\":\"Exo.m Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exom.electric\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filtri UL serie FF per ventilatori compatti, IP54 - EXOM","description":"XGNFF, filtri di protezione completi per ventole, misure: da 105x105mm a 325x325mm, PC\/ABS UL94-V0, grado di protezione: IP54 standard, opzione IP55","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exom-electric.it\/en\/product\/filters-for-fans\/","og_locale":"en_GB","og_type":"article","og_title":"Filtri UL serie FF per ventilatori compatti, IP54 - EXOM","og_description":"XGNFF, filtri di protezione completi per ventole, misure: da 105x105mm a 325x325mm, PC\/ABS UL94-V0, grado di protezione: IP54 standard, opzione IP55","og_url":"https:\/\/exom-electric.it\/en\/product\/filters-for-fans\/","og_site_name":"EXOM ELECTRIC","article_publisher":"https:\/\/www.facebook.com\/exom.electric\/","article_modified_time":"2026-03-03T13:03:52+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2020\/02\/XGNFF_gruppi_filtro_per-_ventilatori.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/","url":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/","name":"Filtri UL serie FF per ventilatori compatti, IP54 - EXOM","isPartOf":{"@id":"https:\/\/exom-electric.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/#primaryimage"},"image":{"@id":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/#primaryimage"},"thumbnailUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2020\/02\/XGNFF_gruppi_filtro_per-_ventilatori.png","datePublished":"2020-02-24T12:21:47+00:00","dateModified":"2026-03-03T13:03:52+00:00","description":"XGNFF, filtri di protezione completi per ventole, misure: da 105x105mm a 325x325mm, PC\/ABS UL94-V0, grado di protezione: IP54 standard, opzione IP55","breadcrumb":{"@id":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/#primaryimage","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2020\/02\/XGNFF_gruppi_filtro_per-_ventilatori.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2020\/02\/XGNFF_gruppi_filtro_per-_ventilatori.png","width":300,"height":300,"caption":"filtri e Gruppi filtro per quadri elettrici"},{"@type":"BreadcrumbList","@id":"https:\/\/exom-electric.it\/prodotto\/filtri-per-ventole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exom-electric.it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/exom-electric.it\/catalogo-exom\/catalogo-prodotti\/"},{"@type":"ListItem","position":3,"name":"Filtri per Ventilatori compatti serie XGNFF"}]},{"@type":"WebSite","@id":"https:\/\/exom-electric.it\/#website","url":"https:\/\/exom-electric.it\/","name":"EXOM ELECTRIC","description":"Automation components - Industrial cable processing","publisher":{"@id":"https:\/\/exom-electric.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exom-electric.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/exom-electric.it\/#organization","name":"Exo.m Electric","url":"https:\/\/exom-electric.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","width":214,"height":100,"caption":"Exo.m Electric"},"image":{"@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exom.electric\/"]}]}},"_links":{"self":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product\/4083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/media\/13456"}],"wp:attachment":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/media?parent=4083"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_brand?post=4083"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat?post=4083"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_tag?post=4083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}