{"id":866,"count":3,"description":"Temporizzatore H5-2 Strumenti gemelli 48x48 con preselezione - tastierina a membrana - zoccolatura undecal.\r\nH7E-3 Strumenti gemelli 34x48, contaimpulsi - contaore - tachimetro - reset frontale - autoalimentato - 7digit.","link":"https:\/\/exom-electric.it\/en\/categoria-prodotto\/temporizzatori-contaimpulsi-digitali-multifunzione\/","name":"Multifunction digital timers and counters","slug":"multifunction-digital-timers-and-counters","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":16,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>temporizzatore digitale, contaimpulsi, digitali a preselezione, multifunzione<\/title>\n<meta name=\"description\" content=\"Temporizzatore, contaimpulsi, digitali a preselezione, multifunzione con memoria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exom-electric.it\/en\/product-category\/multifunction-digital-timers-and-counters\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"temporizzatore digitale, contaimpulsi, digitali a preselezione, multifunzione\" \/>\n<meta property=\"og:description\" content=\"Temporizzatore, contaimpulsi, digitali a preselezione, multifunzione con memoria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exom-electric.it\/en\/product-category\/multifunction-digital-timers-and-counters\/\" \/>\n<meta property=\"og:site_name\" content=\"EXOM ELECTRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/temporizzatori-contaimpulsi-digitali-multifunzione\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/temporizzatori-contaimpulsi-digitali-multifunzione\\\/\",\"name\":\"temporizzatore digitale, contaimpulsi, digitali a preselezione, multifunzione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\"},\"description\":\"Temporizzatore, contaimpulsi, digitali a preselezione, multifunzione con memoria\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/temporizzatori-contaimpulsi-digitali-multifunzione\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/temporizzatori-contaimpulsi-digitali-multifunzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporizzatori - Contaimpulsi digitali Multifunzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"name\":\"EXOM ELECTRIC\",\"description\":\"Automation components - Industrial cable processing\",\"publisher\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exom-electric.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\",\"name\":\"Exo.m Electric\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"width\":214,\"height\":100,\"caption\":\"Exo.m Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exom.electric\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Multifunction digital timers and counters","description":"Multifunction digital timers and counters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exom-electric.it\/en\/product-category\/multifunction-digital-timers-and-counters\/","og_locale":"en_GB","og_type":"article","og_title":"temporizzatore digitale, contaimpulsi, digitali a preselezione, multifunzione","og_description":"Temporizzatore, contaimpulsi, digitali a preselezione, multifunzione con memoria","og_url":"https:\/\/exom-electric.it\/en\/product-category\/multifunction-digital-timers-and-counters\/","og_site_name":"EXOM ELECTRIC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exom-electric.it\/categoria-prodotto\/temporizzatori-contaimpulsi-digitali-multifunzione\/","url":"https:\/\/exom-electric.it\/categoria-prodotto\/temporizzatori-contaimpulsi-digitali-multifunzione\/","name":"Multifunction digital timers and counters","isPartOf":{"@id":"https:\/\/exom-electric.it\/#website"},"description":"Multifunction digital timers and counters","breadcrumb":{"@id":"https:\/\/exom-electric.it\/categoria-prodotto\/temporizzatori-contaimpulsi-digitali-multifunzione\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/exom-electric.it\/categoria-prodotto\/temporizzatori-contaimpulsi-digitali-multifunzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exom-electric.it\/"},{"@type":"ListItem","position":2,"name":"Temporizzatori - Contaimpulsi digitali Multifunzione"}]},{"@type":"WebSite","@id":"https:\/\/exom-electric.it\/#website","url":"https:\/\/exom-electric.it\/","name":"EXOM ELECTRIC","description":"Automation components - Industrial cable processing","publisher":{"@id":"https:\/\/exom-electric.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exom-electric.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/exom-electric.it\/#organization","name":"Exo.m Electric","url":"https:\/\/exom-electric.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","width":214,"height":100,"caption":"Exo.m Electric"},"image":{"@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exom.electric\/"]}]}},"_links":{"self":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat\/866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product?product_cat=866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}