{"id":870,"count":19,"description":"Ventole assiali AC, tecnologia di ventilazione affidabile a marchio Fulltech,\r\nadatti per diverse applicazioni industriali e civili, dal raffreddamento nell'ambito elettronico,\r\nal raffreddamento di tutti i dispositivi ove richieste elevate prestazioni e ingombri ridotti.\r\nDisponibili a cuscinetto o Bronzina.","link":"https:\/\/exom-electric.it\/en\/categoria-prodotto\/ventole-ac\/","name":"AC tube axial fans","slug":"ac-tube-axial-fans","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":19,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ventole assiali AC, ventole 220V 115V, ventole compatte<\/title>\n<meta name=\"description\" content=\"Ventole assiali AC, tecnologia di ventilazione affidabile a marchio Fulltech, adatti per diverse applicazioni industriali e civili.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exom-electric.it\/en\/product-category\/ac-tube-axial-fans\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ventole assiali AC, ventole 220V 115V, ventole compatte\" \/>\n<meta property=\"og:description\" content=\"Ventole assiali AC, tecnologia di ventilazione affidabile a marchio Fulltech, adatti per diverse applicazioni industriali e civili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exom-electric.it\/en\/product-category\/ac-tube-axial-fans\/\" \/>\n<meta property=\"og:site_name\" content=\"EXOM ELECTRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventole-ac\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventole-ac\\\/\",\"name\":\"Ventole assiali AC, ventole 220V 115V, ventole compatte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\"},\"description\":\"Ventole assiali AC, tecnologia di ventilazione affidabile a marchio Fulltech, adatti per diverse applicazioni industriali e civili.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventole-ac\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventole-ac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ventilatori AC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"name\":\"EXOM ELECTRIC\",\"description\":\"Automation components - Industrial cable processing\",\"publisher\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exom-electric.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\",\"name\":\"Exo.m Electric\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"width\":214,\"height\":100,\"caption\":\"Exo.m Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exom.electric\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC tube axial fans","description":"AC tube axial fans, Fulltech brand, used in industrial automation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exom-electric.it\/en\/product-category\/ac-tube-axial-fans\/","og_locale":"en_GB","og_type":"article","og_title":"Ventole assiali AC, ventole 220V 115V, ventole compatte","og_description":"Ventole assiali AC, tecnologia di ventilazione affidabile a marchio Fulltech, adatti per diverse applicazioni industriali e civili.","og_url":"https:\/\/exom-electric.it\/en\/product-category\/ac-tube-axial-fans\/","og_site_name":"EXOM ELECTRIC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exom-electric.it\/categoria-prodotto\/ventole-ac\/","url":"https:\/\/exom-electric.it\/categoria-prodotto\/ventole-ac\/","name":"AC tube axial fans","isPartOf":{"@id":"https:\/\/exom-electric.it\/#website"},"description":"AC tube axial fans, Fulltech brand, used in industrial automation.","breadcrumb":{"@id":"https:\/\/exom-electric.it\/categoria-prodotto\/ventole-ac\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/exom-electric.it\/categoria-prodotto\/ventole-ac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exom-electric.it\/"},{"@type":"ListItem","position":2,"name":"Ventilatori AC"}]},{"@type":"WebSite","@id":"https:\/\/exom-electric.it\/#website","url":"https:\/\/exom-electric.it\/","name":"EXOM ELECTRIC","description":"Automation components - Industrial cable processing","publisher":{"@id":"https:\/\/exom-electric.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exom-electric.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/exom-electric.it\/#organization","name":"Exo.m Electric","url":"https:\/\/exom-electric.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","width":214,"height":100,"caption":"Exo.m Electric"},"image":{"@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exom.electric\/"]}]}},"_links":{"self":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat\/870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product?product_cat=870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}