{"id":872,"count":7,"description":"Wide range of DC tube axial fans. Available ball bearing and sleeve bearing type, 30 cm lead wire connection.\nLow noise and high efficiency, self extinguishing plastic body. Version with PWM and alarm on request.","link":"https:\/\/exom-electric.it\/en\/categoria-prodotto\/ventilatori-cc\/","name":"DC tube axial fans","slug":"cc-tube-axial-fans","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":22,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ventole compatte, ventilatori compatti CC, ventole assiali<\/title>\n<meta name=\"description\" content=\"Ampia selezione di ventilatori assiali CC; versioni a bronzina o cuscinetto. Bassa rumorosit\u00e0 e alta efficienza, su richiesta versioni con PWM ed allarme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exom-electric.it\/en\/product-category\/cc-tube-axial-fans\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ventole compatte, ventilatori compatti CC, ventole assiali\" \/>\n<meta property=\"og:description\" content=\"Ampia selezione di ventilatori assiali CC; versioni a bronzina o cuscinetto. Bassa rumorosit\u00e0 e alta efficienza, su richiesta versioni con PWM ed allarme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exom-electric.it\/en\/product-category\/cc-tube-axial-fans\/\" \/>\n<meta property=\"og:site_name\" content=\"EXOM ELECTRIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventilatori-cc\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventilatori-cc\\\/\",\"name\":\"ventole compatte, ventilatori compatti CC, ventole assiali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\"},\"description\":\"Ampia selezione di ventilatori assiali CC; versioni a bronzina o cuscinetto. Bassa rumorosit\u00e0 e alta efficienza, su richiesta versioni con PWM ed allarme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventilatori-cc\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/categoria-prodotto\\\/ventilatori-cc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/exom-electric.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ventilatori CC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#website\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"name\":\"EXOM ELECTRIC\",\"description\":\"Automation components - Industrial cable processing\",\"publisher\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exom-electric.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#organization\",\"name\":\"Exo.m Electric\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"contentUrl\":\"https:\\\/\\\/exom-electric.it\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/exom-log-blu.png\",\"width\":214,\"height\":100,\"caption\":\"Exo.m Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/exom-electric.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/exom.electric\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DC tube axial fans","description":"DC tube axial fans, sleeve or ball bearing, low noise. Available model with PWM and alarm on request.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exom-electric.it\/en\/product-category\/cc-tube-axial-fans\/","og_locale":"en_GB","og_type":"article","og_title":"ventole compatte, ventilatori compatti CC, ventole assiali","og_description":"Ampia selezione di ventilatori assiali CC; versioni a bronzina o cuscinetto. Bassa rumorosit\u00e0 e alta efficienza, su richiesta versioni con PWM ed allarme.","og_url":"https:\/\/exom-electric.it\/en\/product-category\/cc-tube-axial-fans\/","og_site_name":"EXOM ELECTRIC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exom-electric.it\/categoria-prodotto\/ventilatori-cc\/","url":"https:\/\/exom-electric.it\/categoria-prodotto\/ventilatori-cc\/","name":"DC tube axial fans","isPartOf":{"@id":"https:\/\/exom-electric.it\/#website"},"description":"DC tube axial fans, sleeve or ball bearing, low noise. Available model with PWM and alarm on request.","breadcrumb":{"@id":"https:\/\/exom-electric.it\/categoria-prodotto\/ventilatori-cc\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/exom-electric.it\/categoria-prodotto\/ventilatori-cc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exom-electric.it\/"},{"@type":"ListItem","position":2,"name":"Ventilatori CC"}]},{"@type":"WebSite","@id":"https:\/\/exom-electric.it\/#website","url":"https:\/\/exom-electric.it\/","name":"EXOM ELECTRIC","description":"Automation components - Industrial cable processing","publisher":{"@id":"https:\/\/exom-electric.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exom-electric.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/exom-electric.it\/#organization","name":"Exo.m Electric","url":"https:\/\/exom-electric.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/","url":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","contentUrl":"https:\/\/exom-electric.it\/wp-content\/uploads\/2021\/10\/exom-log-blu.png","width":214,"height":100,"caption":"Exo.m Electric"},"image":{"@id":"https:\/\/exom-electric.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/exom.electric\/"]}]}},"_links":{"self":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat\/872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/exom-electric.it\/en\/wp-json\/wp\/v2\/product?product_cat=872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}